{"id":18463,"date":"2026-07-14T00:01:16","date_gmt":"2026-07-13T23:01:16","guid":{"rendered":"https:\/\/aaq.ch\/?p=18463"},"modified":"2026-07-14T23:29:06","modified_gmt":"2026-07-14T22:29:06","slug":"modification-de-lordonnance-daccreditation-lehe","status":"publish","type":"post","link":"https:\/\/aaq.ch\/fr\/modification-de-lordonnance-daccreditation-lehe\/","title":{"rendered":"Modification de l\u2019ordonnance d\u2019accr\u00e9ditation LEHE"},"content":{"rendered":"<p>Lors de sa s\u00e9ance du 22 mai 2026, le Conseil des hautes \u00e9coles a adopt\u00e9 la modification de l\u2019ordonnance d\u2019accr\u00e9ditation LEHE et fix\u00e9 sa mise en vigueur au 15 juillet 2026. Les principales nouveaut\u00e9s concernent les standards d\u2019accr\u00e9ditation, la dur\u00e9e de validit\u00e9 de l\u2019accr\u00e9ditation, les d\u00e9lais ainsi que l\u2019application de l\u2019ordonnance r\u00e9vis\u00e9e aux proc\u00e9dures en cours et \u00e0 venir.<\/p>\n<p><strong>R\u00e9vision des standards d\u2019accr\u00e9ditation<\/strong><\/p>\n<p>Dans le cadre d\u2019un vaste projet men\u00e9 avec la participation de l\u2019Agence suisse d\u2019accr\u00e9ditation et d\u2019assurance qualit\u00e9 (AAQ) ainsi que des repr\u00e9sentantes et repr\u00e9sentants des hautes \u00e9coles, le Conseil suisse d\u2019accr\u00e9ditation (CSA) a reformul\u00e9 les standards de qualit\u00e9. Cette r\u00e9vision visait \u00e0 les rendre plus pr\u00e9cis et plus clairs. Le cadre l\u00e9gal demeure celui de la loi f\u00e9d\u00e9rale sur l\u2019encouragement et la coordination des hautes \u00e9coles (LEHE).<\/p>\n<p>Les standards sont d\u00e9sormais regroup\u00e9s en trois domaines, au lieu des cinq:<\/p>\n<p><strong>I<\/strong>\u2003Organisation et direction de la haute \u00e9cole, gouvernance et gestion de la qualit\u00e9<br \/>\n<strong>II<\/strong>\u2003Enseignement, recherche et prestations de services<br \/>\n<strong>III<\/strong>\u2003Personnel, finances et infrastructures<\/p>\n<p>L\u2019ancien domaine \u00abCommunication\u00bb a \u00e9t\u00e9 int\u00e9gr\u00e9 aux trois autres domaines. Les domaines \u00abStrat\u00e9gie d\u2019assurance qualit\u00e9\u00bb et \u00abGouvernance\u00bb ont \u00e9t\u00e9 fusionn\u00e9s. Cette nouvelle structure met davantage l\u2019accent sur les activit\u00e9s principales des hautes \u00e9coles. Le nombre de standards passe de 18 \u00e0 23. Enfin, les standards ont \u00e9t\u00e9 simplifi\u00e9s sur le plan r\u00e9dactionnel et formul\u00e9s de mani\u00e8re plus pr\u00e9cise.<\/p>\n<p><strong>Dur\u00e9e de validit\u00e9 de l\u2019accr\u00e9ditation<\/strong><\/p>\n<p>La proc\u00e9dure de renouvellement de l\u2019accr\u00e9ditation (r\u00e9accr\u00e9ditation) demeure, dans son principe, identique \u00e0 celle de la premi\u00e8re accr\u00e9ditation.<\/p>\n<p>La dur\u00e9e de validit\u00e9 est de cinq ans pour une premi\u00e8re accr\u00e9ditation, tandis qu\u2019elle est de huit ans pour une r\u00e9accr\u00e9ditation.<\/p>\n<p>En ce qui concerne la r\u00e9alisation des conditions, l\u2019ordonnance modifi\u00e9e pr\u00e9voit un d\u00e9lai <strong>de six \u00e0 dix-huit mois<\/strong> pour une premi\u00e8re accr\u00e9ditation. Pour une r\u00e9accr\u00e9ditation, ce d\u00e9lai est de <strong>douze \u00e0 vingt-quatre mois<\/strong>.<\/p>\n<p><strong>Dispositions transitoires<\/strong><\/p>\n<p>L\u2019ordonnance d\u2019accr\u00e9ditation modifi\u00e9e ainsi que les standards r\u00e9vis\u00e9s s\u2019appliquent \u00e0 toutes les proc\u00e9dures ouvertes par une agence d\u2019accr\u00e9ditation \u00e0 compter du 15<strong>\u00a0<\/strong>juillet<strong>\u00a0<\/strong>2026. Les proc\u00e9dures de r\u00e9accr\u00e9ditation d\u00e9j\u00e0 en cours b\u00e9n\u00e9ficient \u00e9galement de la prolongation de la dur\u00e9e de validit\u00e9 de l\u2019accr\u00e9ditation \u00e0 huit ans.<\/p>\n<p><strong>Mise en \u0153uvre par l\u2019AAQ<\/strong><\/p>\n<p>L\u2019AAQ a adapt\u00e9 son guide en cons\u00e9quence et a proc\u00e9d\u00e9, sur la base des standards r\u00e9vis\u00e9s, ainsi que des exp\u00e9riences acquises dans le cadre des proc\u00e9dures de r\u00e9accr\u00e9ditation, \u00e0 des ajustements cibl\u00e9s. Ces derniers ont permis de pr\u00e9ciser davantage les principes sur lesquels repose la proc\u00e9dure. Le guide est publi\u00e9 sur le site web de l\u2019AAQ.<\/p>\n<p><strong>Aide \u00e0 l\u2019interpr\u00e9tation du CSA<\/strong><\/p>\n<p>L\u2019aide \u00e0 l\u2019interpr\u00e9tation du Conseil suisse d\u2019accr\u00e9ditation (CSA) relative aux standards de qualit\u00e9 est un instrument d\u2019orientation destin\u00e9 \u00e0 l\u2019ensemble des agences et des hautes \u00e9coles.<\/p>\n<p><strong>S\u00e9ances d\u2019information<\/strong><\/p>\n<p>Pour r\u00e9pondre aux questions concernant la mise en \u0153uvre de l\u2019ordonnance d\u2019accr\u00e9ditation r\u00e9vis\u00e9e, l\u2019AAQ et le secr\u00e9tariat du CSA organiseront conjointement deux webinaires en ao\u00fbt<strong>\u00a0<\/strong>2026. Ces s\u00e9ances pr\u00e9senteront les principales nouveaut\u00e9s des proc\u00e9dures d\u2019accr\u00e9ditation selon la LEHE et offriront l\u2019occasion de poser des questions sur leur mise en \u0153uvre pratique. Les informations relatives aux dates et \u00e0 l\u2019inscription figurent dans la <a href=\"https:\/\/aaq.ch\/fr\/ordonnance-daccreditation-revisee-webinaires-de-laaq-et-du-csa\/\">communication<\/a> correspondante.<\/p>\n<p><strong>Liens Utiles<\/strong><\/p>\n<p><a href=\"https:\/\/www.shk.ch\/fr\">Conf\u00e9rence suisse des hautes \u00e9coles<\/a><\/p>\n<p><a href=\"https:\/\/www.fedlex.admin.ch\/eli\/cc\/2015\/362\/fr\">Ordonnance d\u2019accr\u00e9ditation LEHE<\/a><\/p>\n<p><a href=\"https:\/\/aaq.ch\/fr\/accreditation\/accreditation-institutionnelle\/\">AAQ: Accreditation institutionnelle<\/a><\/p>\n<p><a href=\"https:\/\/akkreditierungsrat.ch\/fr\/download\/aide-a-linterpretation-des-standards-de-qualite-pour-laccreditation-institutionnelle\/?tmstv=1783941986\">Aide \u00e0 l\u2019interpr\u00e9tation des standards de qualit\u00e9 du CSA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors de sa s\u00e9ance du 22 mai 2026, le Conseil des hautes \u00e9coles a adopt\u00e9 la modification de l\u2019ordonnance d\u2019accr\u00e9ditation LEHE et fix\u00e9 sa mise en vigueur au 15 juillet 2026. Les principales nouveaut\u00e9s concernent les standards d\u2019accr\u00e9ditation, la dur\u00e9e de validit\u00e9 de l\u2019accr\u00e9ditation, les d\u00e9lais ainsi que l\u2019application de l\u2019ordonnance r\u00e9vis\u00e9e aux proc\u00e9dures en cours et \u00e0 venir.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"series":[],"_links":{"self":[{"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/posts\/18463"}],"collection":[{"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/comments?post=18463"}],"version-history":[{"count":7,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/posts\/18463\/revisions"}],"predecessor-version":[{"id":18569,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/posts\/18463\/revisions\/18569"}],"wp:attachment":[{"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/media?parent=18463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/categories?post=18463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/tags?post=18463"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/aaq.ch\/fr\/wp-json\/wp\/v2\/series?post=18463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}